{"id":2818,"date":"2026-03-22T10:00:41","date_gmt":"2026-03-22T09:00:41","guid":{"rendered":"https:\/\/lamujerinternahome.wordpress.com\/?p=2818"},"modified":"2026-03-14T09:01:46","modified_gmt":"2026-03-14T08:01:46","slug":"preguntas-al-aire","status":"publish","type":"post","link":"https:\/\/lamujerinterna.com\/en\/2026\/03\/22\/preguntas-al-aire\/","title":{"rendered":"Preguntas al aire"},"content":{"rendered":"<p>\u00bfQui\u00e9n nos hablaba de placer, de deseo, de disfrute cuando \u00e9ramos j\u00f3venes? <\/p>\n\n\n\n<p>\u00bfQui\u00e9n nos explicaba lo que significa poner un l\u00edmite, su relevancia y c\u00f3mo mantenerlo? <\/p>\n\n\n\n<p>\u00bfD\u00f3nde aprendimos a escuchar nuestro sentir o a atender a nuestra intuici\u00f3n?<\/p>\n\n\n\n<p>\u00bfC\u00f3mo nos contaron que descubrir\u00edamos qui\u00e9nes somos y cu\u00e1l es nuestro camino?<\/p>\n\n\n\n<p>\u00bfCon qui\u00e9nes nos sentimos vistas, escuchadas, sostenidas y validadas?<\/p>\n\n\n\n<p>\u00bfCu\u00e1ntas veces vivimos la incomprensi\u00f3n, la frialdad, el abandono o incluso el desprecio?<\/p>\n\n\n\n<p>\u00bfDe qu\u00e9 manera nos trataron para creer que algo estaba mal en nosotras, que \u00e9ramos defectuosas?<\/p>\n\n\n\n<p>\u00bfCu\u00e1ntas l\u00e1grimas nos tragamos para mantener el tipo, para no epatar o evitando que nos hicieran m\u00e1s da\u00f1o?<\/p>\n\n\n\n<p>\u00bfC\u00f3mo se vio afectada nuestra sensibilidad, la confianza en el otro y nuestra capacidad de entrega?<\/p>\n\n\n\n<p>\u00bfEn qu\u00e9 escuela, instituto o facultad ense\u00f1an a ser persona, a Ser?<\/p>\n\n\n\n<p>\u00bfQu\u00e9 familia acompa\u00f1a nuestro proceso de crecimiento y desarrollo como precisamos? <\/p>\n\n\n\n<p>Las preguntas no se agotan.<\/p>\n\n\n\n<p>Las respuestas, aunque a veces se hacen esperar, acaban devel\u00e1ndose.<\/p>\n\n\n\n<p>\u00ab<em>No tengas prisa<\/em>\u00ab, me dice mi Voz, \u00ab<em>sabes que todo llega, en su momento<\/em>\u00ab.<\/p>\n\n\n\n<p>Y yo s\u00e9 que es cierto.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n nos hablaba de placer, de deseo, de disfrute cuando \u00e9ramos j\u00f3venes? \u00bfQui\u00e9n nos explicaba lo que significa poner un l\u00edmite, su relevancia y c\u00f3mo mantenerlo? \u00bfD\u00f3nde aprendimos a escuchar nuestro sentir o a atender a nuestra intuici\u00f3n? \u00bfC\u00f3mo nos contaron que descubrir\u00edamos qui\u00e9nes somos y cu\u00e1l es nuestro camino? \u00bfCon qui\u00e9nes nos sentimos vistas, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":7562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-2818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preguntas al aire - La Mujer Interna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamujerinterna.com\/en\/2026\/03\/22\/preguntas-al-aire\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preguntas al aire - La Mujer Interna\" \/>\n<meta property=\"og:description\" content=\"\u00bfQui\u00e9n nos hablaba de placer, de deseo, de disfrute cuando \u00e9ramos j\u00f3venes? \u00bfQui\u00e9n nos explicaba lo que significa poner un l\u00edmite, su relevancia y c\u00f3mo mantenerlo? \u00bfD\u00f3nde aprendimos a escuchar nuestro sentir o a atender a nuestra intuici\u00f3n? \u00bfC\u00f3mo nos contaron que descubrir\u00edamos qui\u00e9nes somos y cu\u00e1l es nuestro camino? \u00bfCon qui\u00e9nes nos sentimos vistas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamujerinterna.com\/en\/2026\/03\/22\/preguntas-al-aire\/\" \/>\n<meta property=\"og:site_name\" content=\"La Mujer Interna\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-22T09:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gloria Garc\u00eda Ord\u00f3\u00f1ez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gloria Garc\u00eda Ord\u00f3\u00f1ez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/\"},\"author\":{\"name\":\"Gloria Garc\u00eda Ord\u00f3\u00f1ez\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/#\\\/schema\\\/person\\\/28fdb3c82916d1b84ebbc28893e23c49\"},\"headline\":\"Preguntas al aire\",\"datePublished\":\"2026-03-22T09:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/\"},\"wordCount\":205,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/#\\\/schema\\\/person\\\/28fdb3c82916d1b84ebbc28893e23c49\"},\"image\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_20260214_175128-scaled.jpg\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/\",\"url\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/\",\"name\":\"Preguntas al aire - La Mujer Interna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_20260214_175128-scaled.jpg\",\"datePublished\":\"2026-03-22T09:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_20260214_175128-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_20260214_175128-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/2026\\\/03\\\/22\\\/preguntas-al-aire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lamujerinterna.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preguntas al aire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/#website\",\"url\":\"https:\\\/\\\/lamujerinterna.com\\\/\",\"name\":\"La Mujer Interna\",\"description\":\"Acompa\u00f1amiento emocional y espiritual, duelos, ente\u00f3genos, autoconocimiento.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/#\\\/schema\\\/person\\\/28fdb3c82916d1b84ebbc28893e23c49\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamujerinterna.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/#\\\/schema\\\/person\\\/28fdb3c82916d1b84ebbc28893e23c49\",\"name\":\"Gloria Garc\u00eda Ord\u00f3\u00f1ez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png\",\"url\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png\",\"contentUrl\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png\",\"width\":512,\"height\":512,\"caption\":\"Gloria Garc\u00eda Ord\u00f3\u00f1ez\"},\"logo\":{\"@id\":\"https:\\\/\\\/lamujerinterna.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png\"},\"url\":\"https:\\\/\\\/lamujerinterna.com\\\/en\\\/author\\\/gloria\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preguntas al aire - La Mujer Interna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamujerinterna.com\/en\/2026\/03\/22\/preguntas-al-aire\/","og_locale":"en_GB","og_type":"article","og_title":"Preguntas al aire - La Mujer Interna","og_description":"\u00bfQui\u00e9n nos hablaba de placer, de deseo, de disfrute cuando \u00e9ramos j\u00f3venes? \u00bfQui\u00e9n nos explicaba lo que significa poner un l\u00edmite, su relevancia y c\u00f3mo mantenerlo? \u00bfD\u00f3nde aprendimos a escuchar nuestro sentir o a atender a nuestra intuici\u00f3n? \u00bfC\u00f3mo nos contaron que descubrir\u00edamos qui\u00e9nes somos y cu\u00e1l es nuestro camino? \u00bfCon qui\u00e9nes nos sentimos vistas, [&hellip;]","og_url":"https:\/\/lamujerinterna.com\/en\/2026\/03\/22\/preguntas-al-aire\/","og_site_name":"La Mujer Interna","article_published_time":"2026-03-22T09:00:41+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg","type":"image\/jpeg"}],"author":"Gloria Garc\u00eda Ord\u00f3\u00f1ez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gloria Garc\u00eda Ord\u00f3\u00f1ez","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#article","isPartOf":{"@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/"},"author":{"name":"Gloria Garc\u00eda Ord\u00f3\u00f1ez","@id":"https:\/\/lamujerinterna.com\/#\/schema\/person\/28fdb3c82916d1b84ebbc28893e23c49"},"headline":"Preguntas al aire","datePublished":"2026-03-22T09:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/"},"wordCount":205,"commentCount":2,"publisher":{"@id":"https:\/\/lamujerinterna.com\/#\/schema\/person\/28fdb3c82916d1b84ebbc28893e23c49"},"image":{"@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#primaryimage"},"thumbnailUrl":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg","articleSection":["Sin categor\u00eda"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/","url":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/","name":"Preguntas al aire - La Mujer Interna","isPartOf":{"@id":"https:\/\/lamujerinterna.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#primaryimage"},"image":{"@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#primaryimage"},"thumbnailUrl":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg","datePublished":"2026-03-22T09:00:41+00:00","breadcrumb":{"@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#primaryimage","url":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg","contentUrl":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/lamujerinterna.com\/2026\/03\/22\/preguntas-al-aire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lamujerinterna.com\/"},{"@type":"ListItem","position":2,"name":"Preguntas al aire"}]},{"@type":"WebSite","@id":"https:\/\/lamujerinterna.com\/#website","url":"https:\/\/lamujerinterna.com\/","name":"La Mujer Interna","description":"Acompa\u00f1amiento emocional y espiritual, duelos, ente\u00f3genos, autoconocimiento.","publisher":{"@id":"https:\/\/lamujerinterna.com\/#\/schema\/person\/28fdb3c82916d1b84ebbc28893e23c49"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamujerinterna.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/lamujerinterna.com\/#\/schema\/person\/28fdb3c82916d1b84ebbc28893e23c49","name":"Gloria Garc\u00eda Ord\u00f3\u00f1ez","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2025\/11\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png","url":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2025\/11\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png","contentUrl":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2025\/11\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png","width":512,"height":512,"caption":"Gloria Garc\u00eda Ord\u00f3\u00f1ez"},"logo":{"@id":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2025\/11\/cropped-Favicon_Mesa-de-trabajo-1-copia-15-scaled-2.png"},"url":"https:\/\/lamujerinterna.com\/en\/author\/gloria\/"}]}},"jetpack_featured_media_url":"https:\/\/lamujerinterna.com\/wp-content\/uploads\/2026\/03\/IMG_20260214_175128-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/posts\/2818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/comments?post=2818"}],"version-history":[{"count":4,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/posts\/2818\/revisions"}],"predecessor-version":[{"id":7569,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/posts\/2818\/revisions\/7569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/media\/7562"}],"wp:attachment":[{"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/media?parent=2818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/categories?post=2818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lamujerinterna.com\/en\/wp-json\/wp\/v2\/tags?post=2818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}